{"id":1082,"count":1,"description":"","link":"https:\/\/web-demo.my.id\/news2\/tag\/%e0%a6%b8%e0%a6%be%e0%a6%ad%e0%a6%be%e0%a6%b0%e0%a7%87-%e0%a6%b2%e0%a7%87%e0%a6%97%e0%a7%81%e0%a6%a8%e0%a6%be%e0%a6%b0-%e0%a6%a1%e0%a7%8d%e0%a6%b0%e0%a6%be%e0%a6%87%e0%a6%ad%e0%a6%be%e0%a6%b0\/","name":"\u09b8\u09be\u09ad\u09be\u09b0\u09c7 \u09b2\u09c7\u0997\u09c1\u09a8\u09be\u09b0 \u09a1\u09cd\u09b0\u09be\u0987\u09ad\u09be\u09b0 \u09a5\u09c7\u0995\u09c7 \u09a1\u09be\u0995\u09be\u09a4 \u09a6\u09b2\u09c7\u09b0 \u09b8\u09b0\u09cd\u09a6\u09be\u09b0","slug":"%e0%a6%b8%e0%a6%be%e0%a6%ad%e0%a6%be%e0%a6%b0%e0%a7%87-%e0%a6%b2%e0%a7%87%e0%a6%97%e0%a7%81%e0%a6%a8%e0%a6%be%e0%a6%b0-%e0%a6%a1%e0%a7%8d%e0%a6%b0%e0%a6%be%e0%a6%87%e0%a6%ad%e0%a6%be%e0%a6%b0","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/web-demo.my.id\/news2\/wp-json\/wp\/v2\/tags\/1082","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web-demo.my.id\/news2\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/web-demo.my.id\/news2\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/web-demo.my.id\/news2\/wp-json\/wp\/v2\/posts?tags=1082"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}